{"id":10901,"date":"2020-09-22T14:49:49","date_gmt":"2020-09-22T14:49:49","guid":{"rendered":"https:\/\/www.bottegadellearti.net\/?post_type=product&#038;p=10901"},"modified":"2020-11-09T09:22:39","modified_gmt":"2020-11-09T09:22:39","slug":"scatole-portagioie-intarsiate-arcobaleno","status":"publish","type":"product","link":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/","title":{"rendered":"Scatole Portagioie Intarsiate Arcobaleno"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Scatole di legno intarsiato disponibile in diverse misure. Collezione Arcobaleno<\/p>\n","protected":false},"featured_media":10902,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[25],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Scatole Portagioie Intarsiate Arcobaleno - La Bottega delle Arti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scatole Portagioie Intarsiate Arcobaleno - La Bottega delle Arti\" \/>\n<meta property=\"og:description\" content=\"Scatole di legno intarsiato disponibile in diverse misure. Collezione Arcobaleno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/\" \/>\n<meta property=\"og:site_name\" content=\"La Bottega delle Arti\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-09T09:22:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bottegadellearti.net\/wp-content\/uploads\/2020\/09\/coolage-arcobaleno.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/\",\"url\":\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/\",\"name\":\"Scatole Portagioie Intarsiate Arcobaleno - La Bottega delle Arti\",\"isPartOf\":{\"@id\":\"https:\/\/www.bottegadellearti.net\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bottegadellearti.net\/wp-content\/uploads\/2020\/09\/coolage-arcobaleno.png\",\"datePublished\":\"2020-09-22T14:49:49+00:00\",\"dateModified\":\"2020-11-09T09:22:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#primaryimage\",\"url\":\"https:\/\/www.bottegadellearti.net\/wp-content\/uploads\/2020\/09\/coolage-arcobaleno.png\",\"contentUrl\":\"https:\/\/www.bottegadellearti.net\/wp-content\/uploads\/2020\/09\/coolage-arcobaleno.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bottegadellearti.net\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.bottegadellearti.net\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Scatole Portagioie Intarsiate Arcobaleno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bottegadellearti.net\/it\/#website\",\"url\":\"https:\/\/www.bottegadellearti.net\/it\/\",\"name\":\"La Bottega delle Arti\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bottegadellearti.net\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scatole Portagioie Intarsiate Arcobaleno - La Bottega delle Arti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/","og_locale":"it_IT","og_type":"article","og_title":"Scatole Portagioie Intarsiate Arcobaleno - La Bottega delle Arti","og_description":"Scatole di legno intarsiato disponibile in diverse misure. Collezione Arcobaleno","og_url":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/","og_site_name":"La Bottega delle Arti","article_modified_time":"2020-11-09T09:22:39+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.bottegadellearti.net\/wp-content\/uploads\/2020\/09\/coolage-arcobaleno.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/","url":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/","name":"Scatole Portagioie Intarsiate Arcobaleno - La Bottega delle Arti","isPartOf":{"@id":"https:\/\/www.bottegadellearti.net\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#primaryimage"},"image":{"@id":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bottegadellearti.net\/wp-content\/uploads\/2020\/09\/coolage-arcobaleno.png","datePublished":"2020-09-22T14:49:49+00:00","dateModified":"2020-11-09T09:22:39+00:00","breadcrumb":{"@id":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#primaryimage","url":"https:\/\/www.bottegadellearti.net\/wp-content\/uploads\/2020\/09\/coolage-arcobaleno.png","contentUrl":"https:\/\/www.bottegadellearti.net\/wp-content\/uploads\/2020\/09\/coolage-arcobaleno.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.bottegadellearti.net\/it\/prodotto\/scatole-portagioie-intarsiate-arcobaleno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bottegadellearti.net\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.bottegadellearti.net\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Scatole Portagioie Intarsiate Arcobaleno"}]},{"@type":"WebSite","@id":"https:\/\/www.bottegadellearti.net\/it\/#website","url":"https:\/\/www.bottegadellearti.net\/it\/","name":"La Bottega delle Arti","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bottegadellearti.net\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.bottegadellearti.net\/it\/wp-json\/wp\/v2\/product\/10901"}],"collection":[{"href":"https:\/\/www.bottegadellearti.net\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bottegadellearti.net\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bottegadellearti.net\/it\/wp-json\/wp\/v2\/comments?post=10901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bottegadellearti.net\/it\/wp-json\/wp\/v2\/media\/10902"}],"wp:attachment":[{"href":"https:\/\/www.bottegadellearti.net\/it\/wp-json\/wp\/v2\/media?parent=10901"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bottegadellearti.net\/it\/wp-json\/wp\/v2\/product_cat?post=10901"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bottegadellearti.net\/it\/wp-json\/wp\/v2\/product_tag?post=10901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}